{"id":161,"count":1,"description":"","link":"https:\/\/ilariafranchi.com\/en\/tag\/benessere-olistico-en\/","name":"Benessere Olistico","slug":"benessere-olistico-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Benessere Olistico Archives - Ilaria Franchi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ilariafranchi.com\/en\/tag\/benessere-olistico-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Benessere Olistico Archives - Ilaria Franchi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ilariafranchi.com\/en\/tag\/benessere-olistico-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Ilaria Franchi\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ilariafranchi.com\/wp-content\/uploads\/2023\/06\/ilaria-franchi-16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ilariafranchi.com\\\/en\\\/tag\\\/benessere-olistico-en\\\/\",\"url\":\"https:\\\/\\\/ilariafranchi.com\\\/en\\\/tag\\\/benessere-olistico-en\\\/\",\"name\":\"Benessere Olistico Archives - Ilaria Franchi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ilariafranchi.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ilariafranchi.com\\\/en\\\/tag\\\/benessere-olistico-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ilariafranchi.com\\\/en\\\/tag\\\/benessere-olistico-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ilariafranchi.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Benessere Olistico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ilariafranchi.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ilariafranchi.com\\\/en\\\/\",\"name\":\"Ilaria Franchi\",\"description\":\"Wellness Guide\",\"publisher\":{\"@id\":\"https:\\\/\\\/ilariafranchi.com\\\/en\\\/#\\\/schema\\\/person\\\/dc64eeec4f101da91d5934a79bf6dc0f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ilariafranchi.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/ilariafranchi.com\\\/en\\\/#\\\/schema\\\/person\\\/dc64eeec4f101da91d5934a79bf6dc0f\",\"name\":\"Ilaria Franchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ilariafranchi.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/white-blue-transparent-180x180-2.png\",\"url\":\"https:\\\/\\\/ilariafranchi.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/white-blue-transparent-180x180-2.png\",\"contentUrl\":\"https:\\\/\\\/ilariafranchi.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/white-blue-transparent-180x180-2.png\",\"width\":142,\"height\":148,\"caption\":\"Ilaria Franchi\"},\"logo\":{\"@id\":\"https:\\\/\\\/ilariafranchi.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/white-blue-transparent-180x180-2.png\"},\"sameAs\":[\"http:\\\/\\\/ilariafranchi.com\",\"https:\\\/\\\/www.facebook.com\\\/ilariafranchibodysoulguide\",\"https:\\\/\\\/www.instagram.com\\\/ilariafranchi\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Benessere Olistico Archives - Ilaria Franchi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ilariafranchi.com\/en\/tag\/benessere-olistico-en\/","og_locale":"en_US","og_type":"article","og_title":"Benessere Olistico Archives - Ilaria Franchi","og_url":"https:\/\/ilariafranchi.com\/en\/tag\/benessere-olistico-en\/","og_site_name":"Ilaria Franchi","og_image":[{"width":2400,"height":1600,"url":"https:\/\/ilariafranchi.com\/wp-content\/uploads\/2023\/06\/ilaria-franchi-16.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ilariafranchi.com\/en\/tag\/benessere-olistico-en\/","url":"https:\/\/ilariafranchi.com\/en\/tag\/benessere-olistico-en\/","name":"Benessere Olistico Archives - Ilaria Franchi","isPartOf":{"@id":"https:\/\/ilariafranchi.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ilariafranchi.com\/en\/tag\/benessere-olistico-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ilariafranchi.com\/en\/tag\/benessere-olistico-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ilariafranchi.com\/en\/"},{"@type":"ListItem","position":2,"name":"Benessere Olistico"}]},{"@type":"WebSite","@id":"https:\/\/ilariafranchi.com\/en\/#website","url":"https:\/\/ilariafranchi.com\/en\/","name":"Ilaria Franchi","description":"Wellness Guide","publisher":{"@id":"https:\/\/ilariafranchi.com\/en\/#\/schema\/person\/dc64eeec4f101da91d5934a79bf6dc0f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ilariafranchi.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/ilariafranchi.com\/en\/#\/schema\/person\/dc64eeec4f101da91d5934a79bf6dc0f","name":"Ilaria Franchi","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ilariafranchi.com\/wp-content\/uploads\/2023\/06\/white-blue-transparent-180x180-2.png","url":"https:\/\/ilariafranchi.com\/wp-content\/uploads\/2023\/06\/white-blue-transparent-180x180-2.png","contentUrl":"https:\/\/ilariafranchi.com\/wp-content\/uploads\/2023\/06\/white-blue-transparent-180x180-2.png","width":142,"height":148,"caption":"Ilaria Franchi"},"logo":{"@id":"https:\/\/ilariafranchi.com\/wp-content\/uploads\/2023\/06\/white-blue-transparent-180x180-2.png"},"sameAs":["http:\/\/ilariafranchi.com","https:\/\/www.facebook.com\/ilariafranchibodysoulguide","https:\/\/www.instagram.com\/ilariafranchi\/"]}]}},"_links":{"self":[{"href":"https:\/\/ilariafranchi.com\/en\/wp-json\/wp\/v2\/tags\/161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ilariafranchi.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ilariafranchi.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ilariafranchi.com\/en\/wp-json\/wp\/v2\/posts?tags=161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}